{"id":5965,"date":"2019-08-14T16:25:53","date_gmt":"2019-08-14T15:25:53","guid":{"rendered":"http:\/\/www.meprolim.es\/?post_type=product&#038;p=5965"},"modified":"2019-10-29T21:06:29","modified_gmt":"2019-10-29T21:06:29","slug":"escoba-gardenia","status":"publish","type":"product","link":"https:\/\/meprolim.es\/de\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual-de\/escoba-gardenia\/","title":{"rendered":"ESCOBA GARDENIA &#8211; C\u00d3DIGO: CX0005"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<p>Escoba GARDENIA con cerdas de PVC despuntadas.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<ul>\n<li>Soporte de polietileno.<\/li>\n<li>Cerdas de PVC despuntadas.<\/li>\n<li>Cerdas: 18 cm x 3,5 mm \u00d8.<\/li>\n<li>Mechones: 123. Peso: 90 g.<\/li>\n<li>12 uds.\/caja.<\/li>\n<li>31 x 9 x 14 cm.<\/li>\n<\/ul>\n<p><strong>SKU: CX0005<\/strong><\/p>\n","protected":false},"featured_media":5966,"template":"","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":""},"product_brand":[],"product_cat":[334,102],"product_tag":[336,345],"class_list":["post-5965","product","type-product","status-publish","has-post-thumbnail","product_cat-barrido-manual","product_cat-carros-de-servicio-fregado-manual-y-articulos-de-limpieza","product_tag-barrido-manual","product_tag-escoba","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ESCOBA GARDENIA - C\u00d3DIGO: CX0005 - Meprolim<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/meprolim.es\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/escoba-gardenia\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ESCOBA GARDENIA - C\u00d3DIGO: CX0005 - Meprolim\" \/>\n<meta property=\"og:description\" content=\"Soporte de polietileno.  Cerdas de PVC despuntadas.  Cerdas: 18 cm x 3,5 mm \u00d8.  Mechones: 123. Peso: 90 g.  12 uds.\/caja.  31 x 9 x 14 cm.  SKU: CX0005\" \/>\n<meta property=\"og:url\" content=\"https:\/\/meprolim.es\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/escoba-gardenia\/\" \/>\n<meta property=\"og:site_name\" content=\"Meprolim\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-29T21:06:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/CX0005.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual\\\/escoba-gardenia\\\/\",\"url\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual\\\/escoba-gardenia\\\/\",\"name\":\"ESCOBA GARDENIA - C\u00d3DIGO: CX0005 - Meprolim\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual\\\/escoba-gardenia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual\\\/escoba-gardenia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/CX0005.jpg\",\"datePublished\":\"2019-08-14T15:25:53+00:00\",\"dateModified\":\"2019-10-29T21:06:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual\\\/escoba-gardenia\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/meprolim.es\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual\\\/escoba-gardenia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual\\\/escoba-gardenia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/CX0005.jpg\",\"contentUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/CX0005.jpg\",\"width\":768,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual\\\/escoba-gardenia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/meprolim.es\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cat\u00e1logo\",\"item\":\"https:\\\/\\\/meprolim.es\\\/de\\\/catalogo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ESCOBA GARDENIA &#8211; C\u00d3DIGO: CX0005\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\",\"name\":\"Meprolim\",\"description\":\"Cavas Catalanas S.L.\",\"publisher\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#organization\",\"name\":\"Meprolim\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-logo2.png\",\"contentUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-logo2.png\",\"width\":401,\"height\":162,\"caption\":\"Meprolim\"},\"image\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ESCOBA GARDENIA - C\u00d3DIGO: CX0005 - Meprolim","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/meprolim.es\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/escoba-gardenia\/","og_locale":"de_DE","og_type":"article","og_title":"ESCOBA GARDENIA - C\u00d3DIGO: CX0005 - Meprolim","og_description":"Soporte de polietileno.  Cerdas de PVC despuntadas.  Cerdas: 18 cm x 3,5 mm \u00d8.  Mechones: 123. Peso: 90 g.  12 uds.\/caja.  31 x 9 x 14 cm.  SKU: CX0005","og_url":"https:\/\/meprolim.es\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/escoba-gardenia\/","og_site_name":"Meprolim","article_modified_time":"2019-10-29T21:06:29+00:00","og_image":[{"width":768,"height":768,"url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/CX0005.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/meprolim.es\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/escoba-gardenia\/","url":"https:\/\/meprolim.es\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/escoba-gardenia\/","name":"ESCOBA GARDENIA - C\u00d3DIGO: CX0005 - Meprolim","isPartOf":{"@id":"https:\/\/meprolim.es\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/meprolim.es\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/escoba-gardenia\/#primaryimage"},"image":{"@id":"https:\/\/meprolim.es\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/escoba-gardenia\/#primaryimage"},"thumbnailUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/CX0005.jpg","datePublished":"2019-08-14T15:25:53+00:00","dateModified":"2019-10-29T21:06:29+00:00","breadcrumb":{"@id":"https:\/\/meprolim.es\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/escoba-gardenia\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/meprolim.es\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/escoba-gardenia\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/meprolim.es\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/escoba-gardenia\/#primaryimage","url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/CX0005.jpg","contentUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/CX0005.jpg","width":768,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/meprolim.es\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/escoba-gardenia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/meprolim.es\/de\/"},{"@type":"ListItem","position":2,"name":"Cat\u00e1logo","item":"https:\/\/meprolim.es\/de\/catalogo\/"},{"@type":"ListItem","position":3,"name":"ESCOBA GARDENIA &#8211; C\u00d3DIGO: CX0005"}]},{"@type":"WebSite","@id":"https:\/\/meprolim.es\/fr\/#website","url":"https:\/\/meprolim.es\/fr\/","name":"Meprolim","description":"Cavas Catalanas S.L.","publisher":{"@id":"https:\/\/meprolim.es\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/meprolim.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/meprolim.es\/fr\/#organization","name":"Meprolim","url":"https:\/\/meprolim.es\/fr\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/meprolim.es\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/07\/cropped-logo2.png","contentUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/07\/cropped-logo2.png","width":401,"height":162,"caption":"Meprolim"},"image":{"@id":"https:\/\/meprolim.es\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/meprolim.es\/de\/wp-json\/wp\/v2\/product\/5965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meprolim.es\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/meprolim.es\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meprolim.es\/de\/wp-json\/wp\/v2\/media\/5966"}],"wp:attachment":[{"href":"https:\/\/meprolim.es\/de\/wp-json\/wp\/v2\/media?parent=5965"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/meprolim.es\/de\/wp-json\/wp\/v2\/product_brand?post=5965"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/meprolim.es\/de\/wp-json\/wp\/v2\/product_cat?post=5965"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/meprolim.es\/de\/wp-json\/wp\/v2\/product_tag?post=5965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}