{"id":7722,"date":"2019-08-26T13:34:21","date_gmt":"2019-08-26T12:34:21","guid":{"rendered":"http:\/\/www.meprolim.es\/?post_type=product&#038;p=7722"},"modified":"2019-10-27T17:23:35","modified_gmt":"2019-10-27T17:23:35","slug":"cepillo-unas-con-asa","status":"publish","type":"product","link":"https:\/\/meprolim.es\/de\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual-de\/cepillos-escobas-barrido-manual-de\/cepillo-unas-con-asa\/","title":{"rendered":"CEPILLO U\u00d1AS CON ASA &#8211; C\u00d3DIGO: CX0021"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p><strong>SKU: CX0021<\/strong><\/p>\n","protected":false},"featured_media":7723,"template":"","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":""},"product_brand":[],"product_cat":[334,102,1093],"product_tag":[600,487,593],"class_list":["post-7722","product","type-product","status-publish","has-post-thumbnail","product_cat-barrido-manual","product_cat-carros-de-servicio-fregado-manual-y-articulos-de-limpieza","product_cat-cepillos-escobas-barrido-manual","product_tag-cepillo-lavaplatos","product_tag-cocina","product_tag-equipamiento-cocinas","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CEPILLO U\u00d1AS CON ASA - C\u00d3DIGO: CX0021 - Meprolim<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/meprolim.es\/de\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/cepillos-escobas-barrido-manual\/cepillo-unas-con-asa\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CEPILLO U\u00d1AS CON ASA - C\u00d3DIGO: CX0021 - Meprolim\" \/>\n<meta property=\"og:description\" content=\"SKU: CX0021\" \/>\n<meta property=\"og:url\" content=\"https:\/\/meprolim.es\/de\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/cepillos-escobas-barrido-manual\/cepillo-unas-con-asa\/\" \/>\n<meta property=\"og:site_name\" content=\"Meprolim\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-27T17:23:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/CX0021.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/de\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual\\\/cepillos-escobas-barrido-manual\\\/cepillo-unas-con-asa\\\/\",\"url\":\"https:\\\/\\\/meprolim.es\\\/de\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual\\\/cepillos-escobas-barrido-manual\\\/cepillo-unas-con-asa\\\/\",\"name\":\"CEPILLO U\u00d1AS CON ASA - C\u00d3DIGO: CX0021 - Meprolim\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/de\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual\\\/cepillos-escobas-barrido-manual\\\/cepillo-unas-con-asa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/de\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual\\\/cepillos-escobas-barrido-manual\\\/cepillo-unas-con-asa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/CX0021.jpg\",\"datePublished\":\"2019-08-26T12:34:21+00:00\",\"dateModified\":\"2019-10-27T17:23:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/de\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual\\\/cepillos-escobas-barrido-manual\\\/cepillo-unas-con-asa\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/meprolim.es\\\/de\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual\\\/cepillos-escobas-barrido-manual\\\/cepillo-unas-con-asa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/de\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual\\\/cepillos-escobas-barrido-manual\\\/cepillo-unas-con-asa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/CX0021.jpg\",\"contentUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/CX0021.jpg\",\"width\":768,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/de\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual\\\/cepillos-escobas-barrido-manual\\\/cepillo-unas-con-asa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/meprolim.es\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cat\u00e1logo\",\"item\":\"https:\\\/\\\/meprolim.es\\\/de\\\/catalogo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CEPILLO U\u00d1AS CON ASA &#8211; C\u00d3DIGO: CX0021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\",\"name\":\"Meprolim\",\"description\":\"Cavas Catalanas S.L.\",\"publisher\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#organization\",\"name\":\"Meprolim\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-logo2.png\",\"contentUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-logo2.png\",\"width\":401,\"height\":162,\"caption\":\"Meprolim\"},\"image\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CEPILLO U\u00d1AS CON ASA - C\u00d3DIGO: CX0021 - Meprolim","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/meprolim.es\/de\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/cepillos-escobas-barrido-manual\/cepillo-unas-con-asa\/","og_locale":"de_DE","og_type":"article","og_title":"CEPILLO U\u00d1AS CON ASA - C\u00d3DIGO: CX0021 - Meprolim","og_description":"SKU: CX0021","og_url":"https:\/\/meprolim.es\/de\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/cepillos-escobas-barrido-manual\/cepillo-unas-con-asa\/","og_site_name":"Meprolim","article_modified_time":"2019-10-27T17:23:35+00:00","og_image":[{"width":768,"height":768,"url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/CX0021.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/meprolim.es\/de\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/cepillos-escobas-barrido-manual\/cepillo-unas-con-asa\/","url":"https:\/\/meprolim.es\/de\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/cepillos-escobas-barrido-manual\/cepillo-unas-con-asa\/","name":"CEPILLO U\u00d1AS CON ASA - C\u00d3DIGO: CX0021 - Meprolim","isPartOf":{"@id":"https:\/\/meprolim.es\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/meprolim.es\/de\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/cepillos-escobas-barrido-manual\/cepillo-unas-con-asa\/#primaryimage"},"image":{"@id":"https:\/\/meprolim.es\/de\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/cepillos-escobas-barrido-manual\/cepillo-unas-con-asa\/#primaryimage"},"thumbnailUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/CX0021.jpg","datePublished":"2019-08-26T12:34:21+00:00","dateModified":"2019-10-27T17:23:35+00:00","breadcrumb":{"@id":"https:\/\/meprolim.es\/de\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/cepillos-escobas-barrido-manual\/cepillo-unas-con-asa\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/meprolim.es\/de\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/cepillos-escobas-barrido-manual\/cepillo-unas-con-asa\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/meprolim.es\/de\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/cepillos-escobas-barrido-manual\/cepillo-unas-con-asa\/#primaryimage","url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/CX0021.jpg","contentUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/CX0021.jpg","width":768,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/meprolim.es\/de\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/cepillos-escobas-barrido-manual\/cepillo-unas-con-asa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/meprolim.es\/de\/"},{"@type":"ListItem","position":2,"name":"Cat\u00e1logo","item":"https:\/\/meprolim.es\/de\/catalogo\/"},{"@type":"ListItem","position":3,"name":"CEPILLO U\u00d1AS CON ASA &#8211; C\u00d3DIGO: CX0021"}]},{"@type":"WebSite","@id":"https:\/\/meprolim.es\/fr\/#website","url":"https:\/\/meprolim.es\/fr\/","name":"Meprolim","description":"Cavas Catalanas S.L.","publisher":{"@id":"https:\/\/meprolim.es\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/meprolim.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/meprolim.es\/fr\/#organization","name":"Meprolim","url":"https:\/\/meprolim.es\/fr\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/meprolim.es\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/07\/cropped-logo2.png","contentUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/07\/cropped-logo2.png","width":401,"height":162,"caption":"Meprolim"},"image":{"@id":"https:\/\/meprolim.es\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/meprolim.es\/de\/wp-json\/wp\/v2\/product\/7722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meprolim.es\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/meprolim.es\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meprolim.es\/de\/wp-json\/wp\/v2\/media\/7723"}],"wp:attachment":[{"href":"https:\/\/meprolim.es\/de\/wp-json\/wp\/v2\/media?parent=7722"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/meprolim.es\/de\/wp-json\/wp\/v2\/product_brand?post=7722"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/meprolim.es\/de\/wp-json\/wp\/v2\/product_cat?post=7722"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/meprolim.es\/de\/wp-json\/wp\/v2\/product_tag?post=7722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}