{"id":1642,"count":0,"description":"","link":"https:\/\/meprolim.es\/de\/categoria-producto\/dispensadores-celulosa-y-complementos\/papel-servilletas-de-2\/servilletas-de-2\/calidad-tissu-de-2\/","name":"Calidad Tissu","slug":"calidad-tissu-de-2","taxonomy":"product_cat","parent":1639,"meta":[],"menu_order":254,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Calidad Tissu archivos - Meprolim<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/meprolim.es\/de\/categoria-producto\/dispensadores-celulosa-y-complementos\/papel-servilletas-de-2\/servilletas-de-2\/calidad-tissu-de-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Calidad Tissu archivos - Meprolim\" \/>\n<meta property=\"og:url\" content=\"https:\/\/meprolim.es\/de\/categoria-producto\/dispensadores-celulosa-y-complementos\/papel-servilletas-de-2\/servilletas-de-2\/calidad-tissu-de-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Meprolim\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/de\\\/categoria-producto\\\/dispensadores-celulosa-y-complementos\\\/papel-servilletas-de-2\\\/servilletas-de-2\\\/calidad-tissu-de-2\\\/\",\"url\":\"https:\\\/\\\/meprolim.es\\\/de\\\/categoria-producto\\\/dispensadores-celulosa-y-complementos\\\/papel-servilletas-de-2\\\/servilletas-de-2\\\/calidad-tissu-de-2\\\/\",\"name\":\"Calidad Tissu archivos - Meprolim\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/de\\\/categoria-producto\\\/dispensadores-celulosa-y-complementos\\\/papel-servilletas-de-2\\\/servilletas-de-2\\\/calidad-tissu-de-2\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/de\\\/categoria-producto\\\/dispensadores-celulosa-y-complementos\\\/papel-servilletas-de-2\\\/servilletas-de-2\\\/calidad-tissu-de-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/meprolim.es\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dispensadores, Celulosa y Complementos\",\"item\":\"https:\\\/\\\/meprolim.es\\\/de\\\/categoria-producto\\\/dispensadores-celulosa-y-complementos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Papel y Servilletas\",\"item\":\"https:\\\/\\\/meprolim.es\\\/de\\\/categoria-producto\\\/dispensadores-celulosa-y-complementos\\\/papel-servilletas-de-2\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Servilletas\",\"item\":\"https:\\\/\\\/meprolim.es\\\/de\\\/categoria-producto\\\/dispensadores-celulosa-y-complementos\\\/papel-servilletas-de-2\\\/servilletas-de-2\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Calidad Tissu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\",\"name\":\"Meprolim\",\"description\":\"Cavas Catalanas S.L.\",\"publisher\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#organization\",\"name\":\"Meprolim\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-logo2.png\",\"contentUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-logo2.png\",\"width\":401,\"height\":162,\"caption\":\"Meprolim\"},\"image\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Calidad Tissu archivos - Meprolim","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/meprolim.es\/de\/categoria-producto\/dispensadores-celulosa-y-complementos\/papel-servilletas-de-2\/servilletas-de-2\/calidad-tissu-de-2\/","og_locale":"de_DE","og_type":"article","og_title":"Calidad Tissu archivos - Meprolim","og_url":"https:\/\/meprolim.es\/de\/categoria-producto\/dispensadores-celulosa-y-complementos\/papel-servilletas-de-2\/servilletas-de-2\/calidad-tissu-de-2\/","og_site_name":"Meprolim","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/meprolim.es\/de\/categoria-producto\/dispensadores-celulosa-y-complementos\/papel-servilletas-de-2\/servilletas-de-2\/calidad-tissu-de-2\/","url":"https:\/\/meprolim.es\/de\/categoria-producto\/dispensadores-celulosa-y-complementos\/papel-servilletas-de-2\/servilletas-de-2\/calidad-tissu-de-2\/","name":"Calidad Tissu archivos - Meprolim","isPartOf":{"@id":"https:\/\/meprolim.es\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/meprolim.es\/de\/categoria-producto\/dispensadores-celulosa-y-complementos\/papel-servilletas-de-2\/servilletas-de-2\/calidad-tissu-de-2\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/meprolim.es\/de\/categoria-producto\/dispensadores-celulosa-y-complementos\/papel-servilletas-de-2\/servilletas-de-2\/calidad-tissu-de-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/meprolim.es\/de\/"},{"@type":"ListItem","position":2,"name":"Dispensadores, Celulosa y Complementos","item":"https:\/\/meprolim.es\/de\/categoria-producto\/dispensadores-celulosa-y-complementos\/"},{"@type":"ListItem","position":3,"name":"Papel y Servilletas","item":"https:\/\/meprolim.es\/de\/categoria-producto\/dispensadores-celulosa-y-complementos\/papel-servilletas-de-2\/"},{"@type":"ListItem","position":4,"name":"Servilletas","item":"https:\/\/meprolim.es\/de\/categoria-producto\/dispensadores-celulosa-y-complementos\/papel-servilletas-de-2\/servilletas-de-2\/"},{"@type":"ListItem","position":5,"name":"Calidad Tissu"}]},{"@type":"WebSite","@id":"https:\/\/meprolim.es\/fr\/#website","url":"https:\/\/meprolim.es\/fr\/","name":"Meprolim","description":"Cavas Catalanas S.L.","publisher":{"@id":"https:\/\/meprolim.es\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/meprolim.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/meprolim.es\/fr\/#organization","name":"Meprolim","url":"https:\/\/meprolim.es\/fr\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/meprolim.es\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/07\/cropped-logo2.png","contentUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/07\/cropped-logo2.png","width":401,"height":162,"caption":"Meprolim"},"image":{"@id":"https:\/\/meprolim.es\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/meprolim.es\/de\/wp-json\/wp\/v2\/product_cat\/1642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meprolim.es\/de\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/meprolim.es\/de\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/meprolim.es\/de\/wp-json\/wp\/v2\/product_cat\/1639"}],"wp:post_type":[{"href":"https:\/\/meprolim.es\/de\/wp-json\/wp\/v2\/product?product_cat=1642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}