{"id":8308,"date":"2019-08-31T17:31:23","date_gmt":"2019-08-31T16:31:23","guid":{"rendered":"http:\/\/www.meprolim.es\/?post_type=product&#038;p=8308"},"modified":"2023-05-27T18:22:45","modified_gmt":"2023-05-27T17:22:45","slug":"bidon-5kg-aquagen-lvt-top-lavavajillas-manual","status":"publish","type":"product","link":"https:\/\/meprolim.es\/en\/producto\/quimicos-y-articulos-de-limpieza\/productos-quimicos-industriales-en\/lavavajillas-detergentes-abrillantadores-en\/lavavajillas-manuales-en\/bidon-5kg-aquagen-lvt-top-lavavajillas-manual\/","title":{"rendered":"BID\u00d3N 5 KG AQUAGEN TOP LAVAVAJILLAS MANUAL &#8211; C\u00d3DIGO: BX4019"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">Elimina grasa y restos de comida. Brillo sin huellas. Protege las manos. Gran eficacia y acci\u00f3n desengrasante. Evita la irritaci\u00f3n y la sequedad de la piel. Excelentes resultados en vajilla, cuberter\u00eda, cristaler\u00eda, ollas, cacerolas y utensilios similares.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Caracter\u00edsticas:<\/p>\n<ul>\n<li>Gran eficacia y acci\u00f3n desengrasante.<\/li>\n<li>Evita la irritaci\u00f3n y la sequedad de la piel.<\/li>\n<li>Espuma estable y duradera.<\/li>\n<li>Brillo sin huellas.<\/li>\n<li>Excelentes resultados en vajilla, cuberter\u00eda, cristaler\u00eda, ollas, cacerolas y utensilios de cocina similares.<\/li>\n<\/ul>\n<p>Datos t\u00e9cnicos:<\/p>\n<ul>\n<li>pH 6\u00a0<\/li>\n<li>Bid\u00f3n de 5 litros.<\/li>\n<li>Producto l\u00edquido transparente.<\/li>\n<li>Color: verde.<\/li>\n<li>Perfume: lim\u00f3n<\/li>\n<li>Dosificar en el agua de lavado hasta conseguir una espuma abundante.<\/li>\n<li>La dosificaci\u00f3n depende del nivel de suciedad y del n\u00famero de piezas a limpiar.<\/li>\n<li>Sumergir los utensilios y frotar con una esponja, estropajo o cepillo.<\/li>\n<li>Aclarar con agua.<\/li>\n<li>Dejar secar.<\/li>\n<li>Cuando la espuma disminuye debe cambiarse la soluci\u00f3n limpiadora.<\/li>\n<\/ul>\n<p><strong>SKU: BX4019<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":8306,"template":"","meta":[],"product_brand":[],"product_cat":[697,1017,652,94],"product_tag":[487,692,654],"class_list":["post-8308","product","type-product","status-publish","has-post-thumbnail","product_cat-lavavajillas-manuales","product_cat-lavavajillas-detergentes-abrillantadores","product_cat-productos-quimicos-industriales","product_cat-quimicos-articulos-limpieza","product_tag-cocina","product_tag-lavavajillas","product_tag-productos-quimicos","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BID\u00d3N 5 KG AQUAGEN TOP LAVAVAJILLAS MANUAL - C\u00d3DIGO: BX4019 - Meprolim<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/meprolim.es\/producto\/quimicos-articulos-limpieza\/productos-quimicos-industriales\/lavavajillas-detergentes-abrillantadores\/lavavajillas-manuales\/bidon-5kg-aquagen-lvt-top-lavavajillas-manual\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BID\u00d3N 5 KG AQUAGEN TOP LAVAVAJILLAS MANUAL - C\u00d3DIGO: BX4019 - Meprolim\" \/>\n<meta property=\"og:description\" content=\"Caracter\u00edsticas:   Gran eficacia y acci\u00f3n desengrasante.  Evita la irritaci\u00f3n y la sequedad de la piel.  Espuma estable y duradera.  Brillo sin huellas.  Excelentes resultados en vajilla, cuberter\u00eda, cristaler\u00eda, ollas, cacerolas y utensilios de cocina similares.  Datos t\u00e9cnicos:   pH 6\u00a0  Bid\u00f3n de 5 litros.  Producto l\u00edquido transparente.  Color: verde.  Perfume: lim\u00f3n  Dosificar en el agua de lavado hasta conseguir una espuma abundante.  La dosificaci\u00f3n depende del nivel de suciedad y del n\u00famero de piezas a limpiar.  Sumergir los utensilios y frotar con una esponja, estropajo o cepillo.  Aclarar con agua.  Dejar secar.  Cuando la espuma disminuye debe cambiarse la soluci\u00f3n limpiadora.  SKU: BX4019 &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/meprolim.es\/producto\/quimicos-articulos-limpieza\/productos-quimicos-industriales\/lavavajillas-detergentes-abrillantadores\/lavavajillas-manuales\/bidon-5kg-aquagen-lvt-top-lavavajillas-manual\/\" \/>\n<meta property=\"og:site_name\" content=\"Meprolim\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-27T17:22:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/BX4019.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/quimicos-articulos-limpieza\\\/productos-quimicos-industriales\\\/lavavajillas-detergentes-abrillantadores\\\/lavavajillas-manuales\\\/bidon-5kg-aquagen-lvt-top-lavavajillas-manual\\\/\",\"url\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/quimicos-articulos-limpieza\\\/productos-quimicos-industriales\\\/lavavajillas-detergentes-abrillantadores\\\/lavavajillas-manuales\\\/bidon-5kg-aquagen-lvt-top-lavavajillas-manual\\\/\",\"name\":\"BID\u00d3N 5 KG AQUAGEN TOP LAVAVAJILLAS MANUAL - C\u00d3DIGO: BX4019 - Meprolim\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/quimicos-articulos-limpieza\\\/productos-quimicos-industriales\\\/lavavajillas-detergentes-abrillantadores\\\/lavavajillas-manuales\\\/bidon-5kg-aquagen-lvt-top-lavavajillas-manual\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/quimicos-articulos-limpieza\\\/productos-quimicos-industriales\\\/lavavajillas-detergentes-abrillantadores\\\/lavavajillas-manuales\\\/bidon-5kg-aquagen-lvt-top-lavavajillas-manual\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/BX4019.jpg\",\"datePublished\":\"2019-08-31T16:31:23+00:00\",\"dateModified\":\"2023-05-27T17:22:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/quimicos-articulos-limpieza\\\/productos-quimicos-industriales\\\/lavavajillas-detergentes-abrillantadores\\\/lavavajillas-manuales\\\/bidon-5kg-aquagen-lvt-top-lavavajillas-manual\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/meprolim.es\\\/producto\\\/quimicos-articulos-limpieza\\\/productos-quimicos-industriales\\\/lavavajillas-detergentes-abrillantadores\\\/lavavajillas-manuales\\\/bidon-5kg-aquagen-lvt-top-lavavajillas-manual\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/quimicos-articulos-limpieza\\\/productos-quimicos-industriales\\\/lavavajillas-detergentes-abrillantadores\\\/lavavajillas-manuales\\\/bidon-5kg-aquagen-lvt-top-lavavajillas-manual\\\/#primaryimage\",\"url\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/BX4019.jpg\",\"contentUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/BX4019.jpg\",\"width\":768,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/quimicos-articulos-limpieza\\\/productos-quimicos-industriales\\\/lavavajillas-detergentes-abrillantadores\\\/lavavajillas-manuales\\\/bidon-5kg-aquagen-lvt-top-lavavajillas-manual\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/meprolim.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catalogue\",\"item\":\"https:\\\/\\\/meprolim.es\\\/en\\\/catalogue\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BID\u00d3N 5 KG AQUAGEN TOP LAVAVAJILLAS MANUAL &#8211; C\u00d3DIGO: BX4019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\",\"name\":\"Meprolim\",\"description\":\"Cavas Catalanas S.L.\",\"publisher\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#organization\",\"name\":\"Meprolim\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-logo2.png\",\"contentUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-logo2.png\",\"width\":401,\"height\":162,\"caption\":\"Meprolim\"},\"image\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BID\u00d3N 5 KG AQUAGEN TOP LAVAVAJILLAS MANUAL - C\u00d3DIGO: BX4019 - Meprolim","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/meprolim.es\/producto\/quimicos-articulos-limpieza\/productos-quimicos-industriales\/lavavajillas-detergentes-abrillantadores\/lavavajillas-manuales\/bidon-5kg-aquagen-lvt-top-lavavajillas-manual\/","og_locale":"en_US","og_type":"article","og_title":"BID\u00d3N 5 KG AQUAGEN TOP LAVAVAJILLAS MANUAL - C\u00d3DIGO: BX4019 - Meprolim","og_description":"Caracter\u00edsticas:   Gran eficacia y acci\u00f3n desengrasante.  Evita la irritaci\u00f3n y la sequedad de la piel.  Espuma estable y duradera.  Brillo sin huellas.  Excelentes resultados en vajilla, cuberter\u00eda, cristaler\u00eda, ollas, cacerolas y utensilios de cocina similares.  Datos t\u00e9cnicos:   pH 6\u00a0  Bid\u00f3n de 5 litros.  Producto l\u00edquido transparente.  Color: verde.  Perfume: lim\u00f3n  Dosificar en el agua de lavado hasta conseguir una espuma abundante.  La dosificaci\u00f3n depende del nivel de suciedad y del n\u00famero de piezas a limpiar.  Sumergir los utensilios y frotar con una esponja, estropajo o cepillo.  Aclarar con agua.  Dejar secar.  Cuando la espuma disminuye debe cambiarse la soluci\u00f3n limpiadora.  SKU: BX4019 &nbsp;","og_url":"https:\/\/meprolim.es\/producto\/quimicos-articulos-limpieza\/productos-quimicos-industriales\/lavavajillas-detergentes-abrillantadores\/lavavajillas-manuales\/bidon-5kg-aquagen-lvt-top-lavavajillas-manual\/","og_site_name":"Meprolim","article_modified_time":"2023-05-27T17:22:45+00:00","og_image":[{"width":768,"height":768,"url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/BX4019.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/meprolim.es\/producto\/quimicos-articulos-limpieza\/productos-quimicos-industriales\/lavavajillas-detergentes-abrillantadores\/lavavajillas-manuales\/bidon-5kg-aquagen-lvt-top-lavavajillas-manual\/","url":"https:\/\/meprolim.es\/producto\/quimicos-articulos-limpieza\/productos-quimicos-industriales\/lavavajillas-detergentes-abrillantadores\/lavavajillas-manuales\/bidon-5kg-aquagen-lvt-top-lavavajillas-manual\/","name":"BID\u00d3N 5 KG AQUAGEN TOP LAVAVAJILLAS MANUAL - C\u00d3DIGO: BX4019 - Meprolim","isPartOf":{"@id":"https:\/\/meprolim.es\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/meprolim.es\/producto\/quimicos-articulos-limpieza\/productos-quimicos-industriales\/lavavajillas-detergentes-abrillantadores\/lavavajillas-manuales\/bidon-5kg-aquagen-lvt-top-lavavajillas-manual\/#primaryimage"},"image":{"@id":"https:\/\/meprolim.es\/producto\/quimicos-articulos-limpieza\/productos-quimicos-industriales\/lavavajillas-detergentes-abrillantadores\/lavavajillas-manuales\/bidon-5kg-aquagen-lvt-top-lavavajillas-manual\/#primaryimage"},"thumbnailUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/BX4019.jpg","datePublished":"2019-08-31T16:31:23+00:00","dateModified":"2023-05-27T17:22:45+00:00","breadcrumb":{"@id":"https:\/\/meprolim.es\/producto\/quimicos-articulos-limpieza\/productos-quimicos-industriales\/lavavajillas-detergentes-abrillantadores\/lavavajillas-manuales\/bidon-5kg-aquagen-lvt-top-lavavajillas-manual\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/meprolim.es\/producto\/quimicos-articulos-limpieza\/productos-quimicos-industriales\/lavavajillas-detergentes-abrillantadores\/lavavajillas-manuales\/bidon-5kg-aquagen-lvt-top-lavavajillas-manual\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/meprolim.es\/producto\/quimicos-articulos-limpieza\/productos-quimicos-industriales\/lavavajillas-detergentes-abrillantadores\/lavavajillas-manuales\/bidon-5kg-aquagen-lvt-top-lavavajillas-manual\/#primaryimage","url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/BX4019.jpg","contentUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/BX4019.jpg","width":768,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/meprolim.es\/producto\/quimicos-articulos-limpieza\/productos-quimicos-industriales\/lavavajillas-detergentes-abrillantadores\/lavavajillas-manuales\/bidon-5kg-aquagen-lvt-top-lavavajillas-manual\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/meprolim.es\/en\/"},{"@type":"ListItem","position":2,"name":"Catalogue","item":"https:\/\/meprolim.es\/en\/catalogue\/"},{"@type":"ListItem","position":3,"name":"BID\u00d3N 5 KG AQUAGEN TOP LAVAVAJILLAS MANUAL &#8211; C\u00d3DIGO: BX4019"}]},{"@type":"WebSite","@id":"https:\/\/meprolim.es\/fr\/#website","url":"https:\/\/meprolim.es\/fr\/","name":"Meprolim","description":"Cavas Catalanas S.L.","publisher":{"@id":"https:\/\/meprolim.es\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/meprolim.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/meprolim.es\/fr\/#organization","name":"Meprolim","url":"https:\/\/meprolim.es\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/meprolim.es\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/07\/cropped-logo2.png","contentUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/07\/cropped-logo2.png","width":401,"height":162,"caption":"Meprolim"},"image":{"@id":"https:\/\/meprolim.es\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/product\/8308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/media\/8306"}],"wp:attachment":[{"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/media?parent=8308"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/product_brand?post=8308"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/product_cat?post=8308"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/product_tag?post=8308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}