{"id":8586,"date":"2019-09-02T13:35:51","date_gmt":"2019-09-02T12:35:51","guid":{"rendered":"http:\/\/www.meprolim.es\/?post_type=product&#038;p=8586"},"modified":"2023-05-22T16:33:17","modified_gmt":"2023-05-22T15:33:17","slug":"bidon-2340kg-lavicom-nt-neutralizante","status":"publish","type":"product","link":"https:\/\/meprolim.es\/en\/producto\/quimicos-y-articulos-de-limpieza\/productos-quimicos-industriales-en\/lavanderia-en\/suavisantes-en\/bidon-2340kg-lavicom-nt-neutralizante\/","title":{"rendered":"BID\u00d3N 23,40KG LAVICOM NT NEUTRALIZANTE &#8211; C\u00d3DIGO: BX4126"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">Neutralizacion efectiva de la alcalinidad residual y restos de blanqueante clorado en el agua del ultimo aclarado y en la ropa. Evita que los tejidos se da\u00f1en o amarilleen. Alarga la vida de las prendas.<\/p>\n<p>&nbsp;<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Caracter\u00edsticas:<\/p>\n<ul>\n<li>Neutralizaci\u00f3n efectiva de la alcalinidad residual y restos de blanqueante clorado en el agua del \u00faltimo aclarado y en la ropa.<\/li>\n<li>Evita que los tejidos se da\u00f1en o amarilleen.<\/li>\n<li>Alarga la vida de las prendas.<\/li>\n<\/ul>\n<p>Datos t\u00e9cnicos:<\/p>\n<ul>\n<li>pH 3.<\/li>\n<li>Producto l\u00edquido transparente.<\/li>\n<li>Color: amarillo.<\/li>\n<li>Perfume: caracter\u00edstico.<\/li>\n<li>Dosificar 1-3 gramos de producto por kilo de ropa, en el \u00faltimo aclarado.<\/li>\n<li>Uso autom\u00e1tico en sistemas LAVAMATIC.<\/li>\n<\/ul>\n<p><strong>SKU: BX4126<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":8587,"template":"","meta":[],"product_brand":[],"product_cat":[1049,652,94,1053],"product_tag":[727,654],"class_list":["post-8586","product","type-product","status-publish","has-post-thumbnail","product_cat-lavanderia","product_cat-productos-quimicos-industriales","product_cat-quimicos-articulos-limpieza","product_cat-suavisantes","product_tag-lavanderia","product_tag-productos-quimicos","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BID\u00d3N 23,40KG LAVICOM NT NEUTRALIZANTE - C\u00d3DIGO: BX4126 - Meprolim<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/meprolim.es\/producto\/quimicos-articulos-limpieza\/productos-quimicos-industriales\/lavanderia\/suavisantes\/bidon-2340kg-lavicom-nt-neutralizante\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BID\u00d3N 23,40KG LAVICOM NT NEUTRALIZANTE - C\u00d3DIGO: BX4126 - Meprolim\" \/>\n<meta property=\"og:description\" content=\"Caracter\u00edsticas:   Neutralizaci\u00f3n efectiva de la alcalinidad residual y restos de blanqueante clorado en el agua del \u00faltimo aclarado y en la ropa.  Evita que los tejidos se da\u00f1en o amarilleen.  Alarga la vida de las prendas.  Datos t\u00e9cnicos:   pH 3.  Producto l\u00edquido transparente.  Color: amarillo.  Perfume: caracter\u00edstico.  Dosificar 1-3 gramos de producto por kilo de ropa, en el \u00faltimo aclarado.  Uso autom\u00e1tico en sistemas LAVAMATIC.  SKU: BX4126  &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/meprolim.es\/producto\/quimicos-articulos-limpieza\/productos-quimicos-industriales\/lavanderia\/suavisantes\/bidon-2340kg-lavicom-nt-neutralizante\/\" \/>\n<meta property=\"og:site_name\" content=\"Meprolim\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-22T15:33:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/09\/BX4126.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1417\" \/>\n\t<meta property=\"og:image:height\" content=\"1417\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/quimicos-articulos-limpieza\\\/productos-quimicos-industriales\\\/lavanderia\\\/suavisantes\\\/bidon-2340kg-lavicom-nt-neutralizante\\\/\",\"url\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/quimicos-articulos-limpieza\\\/productos-quimicos-industriales\\\/lavanderia\\\/suavisantes\\\/bidon-2340kg-lavicom-nt-neutralizante\\\/\",\"name\":\"BID\u00d3N 23,40KG LAVICOM NT NEUTRALIZANTE - C\u00d3DIGO: BX4126 - Meprolim\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/quimicos-articulos-limpieza\\\/productos-quimicos-industriales\\\/lavanderia\\\/suavisantes\\\/bidon-2340kg-lavicom-nt-neutralizante\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/quimicos-articulos-limpieza\\\/productos-quimicos-industriales\\\/lavanderia\\\/suavisantes\\\/bidon-2340kg-lavicom-nt-neutralizante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/BX4126.jpg\",\"datePublished\":\"2019-09-02T12:35:51+00:00\",\"dateModified\":\"2023-05-22T15:33:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/quimicos-articulos-limpieza\\\/productos-quimicos-industriales\\\/lavanderia\\\/suavisantes\\\/bidon-2340kg-lavicom-nt-neutralizante\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/meprolim.es\\\/producto\\\/quimicos-articulos-limpieza\\\/productos-quimicos-industriales\\\/lavanderia\\\/suavisantes\\\/bidon-2340kg-lavicom-nt-neutralizante\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/quimicos-articulos-limpieza\\\/productos-quimicos-industriales\\\/lavanderia\\\/suavisantes\\\/bidon-2340kg-lavicom-nt-neutralizante\\\/#primaryimage\",\"url\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/BX4126.jpg\",\"contentUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/BX4126.jpg\",\"width\":1417,\"height\":1417},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/producto\\\/quimicos-articulos-limpieza\\\/productos-quimicos-industriales\\\/lavanderia\\\/suavisantes\\\/bidon-2340kg-lavicom-nt-neutralizante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/meprolim.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catalogue\",\"item\":\"https:\\\/\\\/meprolim.es\\\/en\\\/catalogue\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BID\u00d3N 23,40KG LAVICOM NT NEUTRALIZANTE &#8211; C\u00d3DIGO: BX4126\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\",\"name\":\"Meprolim\",\"description\":\"Cavas Catalanas S.L.\",\"publisher\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#organization\",\"name\":\"Meprolim\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-logo2.png\",\"contentUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-logo2.png\",\"width\":401,\"height\":162,\"caption\":\"Meprolim\"},\"image\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BID\u00d3N 23,40KG LAVICOM NT NEUTRALIZANTE - C\u00d3DIGO: BX4126 - Meprolim","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/meprolim.es\/producto\/quimicos-articulos-limpieza\/productos-quimicos-industriales\/lavanderia\/suavisantes\/bidon-2340kg-lavicom-nt-neutralizante\/","og_locale":"en_US","og_type":"article","og_title":"BID\u00d3N 23,40KG LAVICOM NT NEUTRALIZANTE - C\u00d3DIGO: BX4126 - Meprolim","og_description":"Caracter\u00edsticas:   Neutralizaci\u00f3n efectiva de la alcalinidad residual y restos de blanqueante clorado en el agua del \u00faltimo aclarado y en la ropa.  Evita que los tejidos se da\u00f1en o amarilleen.  Alarga la vida de las prendas.  Datos t\u00e9cnicos:   pH 3.  Producto l\u00edquido transparente.  Color: amarillo.  Perfume: caracter\u00edstico.  Dosificar 1-3 gramos de producto por kilo de ropa, en el \u00faltimo aclarado.  Uso autom\u00e1tico en sistemas LAVAMATIC.  SKU: BX4126  &nbsp;","og_url":"https:\/\/meprolim.es\/producto\/quimicos-articulos-limpieza\/productos-quimicos-industriales\/lavanderia\/suavisantes\/bidon-2340kg-lavicom-nt-neutralizante\/","og_site_name":"Meprolim","article_modified_time":"2023-05-22T15:33:17+00:00","og_image":[{"width":1417,"height":1417,"url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/09\/BX4126.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/meprolim.es\/producto\/quimicos-articulos-limpieza\/productos-quimicos-industriales\/lavanderia\/suavisantes\/bidon-2340kg-lavicom-nt-neutralizante\/","url":"https:\/\/meprolim.es\/producto\/quimicos-articulos-limpieza\/productos-quimicos-industriales\/lavanderia\/suavisantes\/bidon-2340kg-lavicom-nt-neutralizante\/","name":"BID\u00d3N 23,40KG LAVICOM NT NEUTRALIZANTE - C\u00d3DIGO: BX4126 - Meprolim","isPartOf":{"@id":"https:\/\/meprolim.es\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/meprolim.es\/producto\/quimicos-articulos-limpieza\/productos-quimicos-industriales\/lavanderia\/suavisantes\/bidon-2340kg-lavicom-nt-neutralizante\/#primaryimage"},"image":{"@id":"https:\/\/meprolim.es\/producto\/quimicos-articulos-limpieza\/productos-quimicos-industriales\/lavanderia\/suavisantes\/bidon-2340kg-lavicom-nt-neutralizante\/#primaryimage"},"thumbnailUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/09\/BX4126.jpg","datePublished":"2019-09-02T12:35:51+00:00","dateModified":"2023-05-22T15:33:17+00:00","breadcrumb":{"@id":"https:\/\/meprolim.es\/producto\/quimicos-articulos-limpieza\/productos-quimicos-industriales\/lavanderia\/suavisantes\/bidon-2340kg-lavicom-nt-neutralizante\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/meprolim.es\/producto\/quimicos-articulos-limpieza\/productos-quimicos-industriales\/lavanderia\/suavisantes\/bidon-2340kg-lavicom-nt-neutralizante\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/meprolim.es\/producto\/quimicos-articulos-limpieza\/productos-quimicos-industriales\/lavanderia\/suavisantes\/bidon-2340kg-lavicom-nt-neutralizante\/#primaryimage","url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/09\/BX4126.jpg","contentUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/09\/BX4126.jpg","width":1417,"height":1417},{"@type":"BreadcrumbList","@id":"https:\/\/meprolim.es\/producto\/quimicos-articulos-limpieza\/productos-quimicos-industriales\/lavanderia\/suavisantes\/bidon-2340kg-lavicom-nt-neutralizante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/meprolim.es\/en\/"},{"@type":"ListItem","position":2,"name":"Catalogue","item":"https:\/\/meprolim.es\/en\/catalogue\/"},{"@type":"ListItem","position":3,"name":"BID\u00d3N 23,40KG LAVICOM NT NEUTRALIZANTE &#8211; C\u00d3DIGO: BX4126"}]},{"@type":"WebSite","@id":"https:\/\/meprolim.es\/fr\/#website","url":"https:\/\/meprolim.es\/fr\/","name":"Meprolim","description":"Cavas Catalanas S.L.","publisher":{"@id":"https:\/\/meprolim.es\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/meprolim.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/meprolim.es\/fr\/#organization","name":"Meprolim","url":"https:\/\/meprolim.es\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/meprolim.es\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/07\/cropped-logo2.png","contentUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/07\/cropped-logo2.png","width":401,"height":162,"caption":"Meprolim"},"image":{"@id":"https:\/\/meprolim.es\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/product\/8586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/media\/8587"}],"wp:attachment":[{"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/media?parent=8586"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/product_brand?post=8586"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/product_cat?post=8586"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/product_tag?post=8586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}