{"id":2640,"count":0,"description":"","link":"https:\/\/meprolim.es\/en\/categoria-producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual-en\/mopas-en\/mopa-chasis-en-2\/","name":"Mopa con Chasis","slug":"mopa-chasis-en-2","taxonomy":"product_cat","parent":2638,"meta":[],"menu_order":79,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mopa con Chasis archivos - Meprolim<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/meprolim.es\/en\/categoria-producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual-en\/mopas-en\/mopa-chasis-en-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mopa con Chasis archivos - Meprolim\" \/>\n<meta property=\"og:url\" content=\"https:\/\/meprolim.es\/en\/categoria-producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual-en\/mopas-en\/mopa-chasis-en-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Meprolim\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/en\\\/categoria-producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual-en\\\/mopas-en\\\/mopa-chasis-en-2\\\/\",\"url\":\"https:\\\/\\\/meprolim.es\\\/en\\\/categoria-producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual-en\\\/mopas-en\\\/mopa-chasis-en-2\\\/\",\"name\":\"Mopa con Chasis archivos - Meprolim\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/en\\\/categoria-producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual-en\\\/mopas-en\\\/mopa-chasis-en-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/en\\\/categoria-producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual-en\\\/mopas-en\\\/mopa-chasis-en-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/meprolim.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carros de Servicio, Fregado Manual y Art\u00edculos de Limpieza\",\"item\":\"https:\\\/\\\/meprolim.es\\\/en\\\/categoria-producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Barrido Manual\",\"item\":\"https:\\\/\\\/meprolim.es\\\/en\\\/categoria-producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual-en\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Mopas\",\"item\":\"https:\\\/\\\/meprolim.es\\\/en\\\/categoria-producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual-en\\\/mopas-en\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Mopa con Chasis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\",\"name\":\"Meprolim\",\"description\":\"Cavas Catalanas S.L.\",\"publisher\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#organization\",\"name\":\"Meprolim\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-logo2.png\",\"contentUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-logo2.png\",\"width\":401,\"height\":162,\"caption\":\"Meprolim\"},\"image\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mopa con Chasis archivos - Meprolim","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/meprolim.es\/en\/categoria-producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual-en\/mopas-en\/mopa-chasis-en-2\/","og_locale":"en_US","og_type":"article","og_title":"Mopa con Chasis archivos - Meprolim","og_url":"https:\/\/meprolim.es\/en\/categoria-producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual-en\/mopas-en\/mopa-chasis-en-2\/","og_site_name":"Meprolim","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/meprolim.es\/en\/categoria-producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual-en\/mopas-en\/mopa-chasis-en-2\/","url":"https:\/\/meprolim.es\/en\/categoria-producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual-en\/mopas-en\/mopa-chasis-en-2\/","name":"Mopa con Chasis archivos - Meprolim","isPartOf":{"@id":"https:\/\/meprolim.es\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/meprolim.es\/en\/categoria-producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual-en\/mopas-en\/mopa-chasis-en-2\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/meprolim.es\/en\/categoria-producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual-en\/mopas-en\/mopa-chasis-en-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/meprolim.es\/en\/"},{"@type":"ListItem","position":2,"name":"Carros de Servicio, Fregado Manual y Art\u00edculos de Limpieza","item":"https:\/\/meprolim.es\/en\/categoria-producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/"},{"@type":"ListItem","position":3,"name":"Barrido Manual","item":"https:\/\/meprolim.es\/en\/categoria-producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual-en\/"},{"@type":"ListItem","position":4,"name":"Mopas","item":"https:\/\/meprolim.es\/en\/categoria-producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual-en\/mopas-en\/"},{"@type":"ListItem","position":5,"name":"Mopa con Chasis"}]},{"@type":"WebSite","@id":"https:\/\/meprolim.es\/fr\/#website","url":"https:\/\/meprolim.es\/fr\/","name":"Meprolim","description":"Cavas Catalanas S.L.","publisher":{"@id":"https:\/\/meprolim.es\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/meprolim.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/meprolim.es\/fr\/#organization","name":"Meprolim","url":"https:\/\/meprolim.es\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/meprolim.es\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/07\/cropped-logo2.png","contentUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/07\/cropped-logo2.png","width":401,"height":162,"caption":"Meprolim"},"image":{"@id":"https:\/\/meprolim.es\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/product_cat\/2640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/product_cat\/2638"}],"wp:post_type":[{"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/product?product_cat=2640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}