{"id":3065,"count":0,"description":"","link":"https:\/\/meprolim.es\/en\/categoria-producto\/maquinaria-de-limpieza\/barredoras-en\/barredoras-manuales-en\/","name":"Barredoras Manuales","slug":"barredoras-manuales-en","taxonomy":"product_cat","parent":3062,"meta":[],"menu_order":13,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Barredoras Manuales archivos - Meprolim<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/meprolim.es\/en\/categoria-producto\/maquinaria-de-limpieza\/barredoras-en\/barredoras-manuales-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Barredoras Manuales archivos - Meprolim\" \/>\n<meta property=\"og:url\" content=\"https:\/\/meprolim.es\/en\/categoria-producto\/maquinaria-de-limpieza\/barredoras-en\/barredoras-manuales-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Meprolim\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/en\\\/categoria-producto\\\/maquinaria-de-limpieza\\\/barredoras-en\\\/barredoras-manuales-en\\\/\",\"url\":\"https:\\\/\\\/meprolim.es\\\/en\\\/categoria-producto\\\/maquinaria-de-limpieza\\\/barredoras-en\\\/barredoras-manuales-en\\\/\",\"name\":\"Barredoras Manuales archivos - Meprolim\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/en\\\/categoria-producto\\\/maquinaria-de-limpieza\\\/barredoras-en\\\/barredoras-manuales-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/en\\\/categoria-producto\\\/maquinaria-de-limpieza\\\/barredoras-en\\\/barredoras-manuales-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/meprolim.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Maquinaria de Limpieza\",\"item\":\"https:\\\/\\\/meprolim.es\\\/en\\\/categoria-producto\\\/maquinaria-de-limpieza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Barredoras\",\"item\":\"https:\\\/\\\/meprolim.es\\\/en\\\/categoria-producto\\\/maquinaria-de-limpieza\\\/barredoras-en\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Barredoras Manuales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\",\"name\":\"Meprolim\",\"description\":\"Cavas Catalanas S.L.\",\"publisher\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#organization\",\"name\":\"Meprolim\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-logo2.png\",\"contentUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-logo2.png\",\"width\":401,\"height\":162,\"caption\":\"Meprolim\"},\"image\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Barredoras Manuales archivos - Meprolim","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/meprolim.es\/en\/categoria-producto\/maquinaria-de-limpieza\/barredoras-en\/barredoras-manuales-en\/","og_locale":"en_US","og_type":"article","og_title":"Barredoras Manuales archivos - Meprolim","og_url":"https:\/\/meprolim.es\/en\/categoria-producto\/maquinaria-de-limpieza\/barredoras-en\/barredoras-manuales-en\/","og_site_name":"Meprolim","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/meprolim.es\/en\/categoria-producto\/maquinaria-de-limpieza\/barredoras-en\/barredoras-manuales-en\/","url":"https:\/\/meprolim.es\/en\/categoria-producto\/maquinaria-de-limpieza\/barredoras-en\/barredoras-manuales-en\/","name":"Barredoras Manuales archivos - Meprolim","isPartOf":{"@id":"https:\/\/meprolim.es\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/meprolim.es\/en\/categoria-producto\/maquinaria-de-limpieza\/barredoras-en\/barredoras-manuales-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/meprolim.es\/en\/categoria-producto\/maquinaria-de-limpieza\/barredoras-en\/barredoras-manuales-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/meprolim.es\/en\/"},{"@type":"ListItem","position":2,"name":"Maquinaria de Limpieza","item":"https:\/\/meprolim.es\/en\/categoria-producto\/maquinaria-de-limpieza\/"},{"@type":"ListItem","position":3,"name":"Barredoras","item":"https:\/\/meprolim.es\/en\/categoria-producto\/maquinaria-de-limpieza\/barredoras-en\/"},{"@type":"ListItem","position":4,"name":"Barredoras Manuales"}]},{"@type":"WebSite","@id":"https:\/\/meprolim.es\/fr\/#website","url":"https:\/\/meprolim.es\/fr\/","name":"Meprolim","description":"Cavas Catalanas S.L.","publisher":{"@id":"https:\/\/meprolim.es\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/meprolim.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/meprolim.es\/fr\/#organization","name":"Meprolim","url":"https:\/\/meprolim.es\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/meprolim.es\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/07\/cropped-logo2.png","contentUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/07\/cropped-logo2.png","width":401,"height":162,"caption":"Meprolim"},"image":{"@id":"https:\/\/meprolim.es\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/product_cat\/3065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/product_cat\/3062"}],"wp:post_type":[{"href":"https:\/\/meprolim.es\/en\/wp-json\/wp\/v2\/product?product_cat=3065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}