{"id":5909,"date":"2019-08-13T18:56:42","date_gmt":"2019-08-13T17:56:42","guid":{"rendered":"http:\/\/www.meprolim.es\/?post_type=product&#038;p=5909"},"modified":"2019-10-29T19:17:33","modified_gmt":"2019-10-29T19:17:33","slug":"caja-2-rollos-de-fibra-easy-trap-3m-38mt-x-127mm","status":"publish","type":"product","link":"https:\/\/meprolim.es\/fr\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual-fr\/atrapolvos-fr\/caja-2-rollos-de-fibra-easy-trap-3m-38mt-x-127mm\/","title":{"rendered":"CAJA 2 ROLLOS DE FIBRA EASY TRAP 3M 38mt x 127mm &#8211; C\u00d3DIGO: AM0009"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<p>Rollo de fibra Easy Trap 3M de 38 metros x 127 mil\u00edmetros.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<ul>\n<li>Caja 2 rollos 12,7 x 380 cm<\/li>\n<li>Atrapa y retiene hasta seis veces m\u00e1s cantidad de polvo, suciedad y pelo que otras mopas tradicionales.<\/li>\n<li>Dos anchos para adaptarse a cualquier soporte.<\/li>\n<li>No deja residuos ni resinas sobre el suelo.<\/li>\n<li>Pa\u00f1os recortados para facilitar su uso.<\/li>\n<\/ul>\n<p><strong>SKU: AM0009<\/strong><\/p>\n","protected":false},"featured_media":5910,"template":"","meta":[],"product_brand":[],"product_cat":[341,334,102],"product_tag":[342,336],"class_list":{"0":"post-5909","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-atrapolvos","7":"product_cat-barrido-manual","8":"product_cat-carros-de-servicio-fregado-manual-y-articulos-de-limpieza","9":"product_tag-atrapapolvo","10":"product_tag-barrido-manual","12":"first","13":"instock","14":"shipping-taxable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CAJA 2 ROLLOS DE FIBRA EASY TRAP 3M 38mt x 127mm - C\u00d3DIGO: AM0009 - Meprolim<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/meprolim.es\/fr\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/atrapolvos\/caja-2-rollos-de-fibra-easy-trap-3m-38mt-x-127mm\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CAJA 2 ROLLOS DE FIBRA EASY TRAP 3M 38mt x 127mm - C\u00d3DIGO: AM0009 - Meprolim\" \/>\n<meta property=\"og:description\" content=\"Caja 2 rollos 12,7 x 380 cm  Atrapa y retiene hasta seis veces m\u00e1s cantidad de polvo, suciedad y pelo que otras mopas tradicionales.  Dos anchos para adaptarse a cualquier soporte.  No deja residuos ni resinas sobre el suelo.  Pa\u00f1os recortados para facilitar su uso.  SKU: AM0009\" \/>\n<meta property=\"og:url\" content=\"https:\/\/meprolim.es\/fr\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/atrapolvos\/caja-2-rollos-de-fibra-easy-trap-3m-38mt-x-127mm\/\" \/>\n<meta property=\"og:site_name\" content=\"Meprolim\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-29T19:17:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/AM0009.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual\\\/atrapolvos\\\/caja-2-rollos-de-fibra-easy-trap-3m-38mt-x-127mm\\\/\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual\\\/atrapolvos\\\/caja-2-rollos-de-fibra-easy-trap-3m-38mt-x-127mm\\\/\",\"name\":\"CAJA 2 ROLLOS DE FIBRA EASY TRAP 3M 38mt x 127mm - C\u00d3DIGO: AM0009 - Meprolim\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual\\\/atrapolvos\\\/caja-2-rollos-de-fibra-easy-trap-3m-38mt-x-127mm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual\\\/atrapolvos\\\/caja-2-rollos-de-fibra-easy-trap-3m-38mt-x-127mm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/AM0009.jpg\",\"datePublished\":\"2019-08-13T17:56:42+00:00\",\"dateModified\":\"2019-10-29T19:17:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual\\\/atrapolvos\\\/caja-2-rollos-de-fibra-easy-trap-3m-38mt-x-127mm\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/meprolim.es\\\/fr\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual\\\/atrapolvos\\\/caja-2-rollos-de-fibra-easy-trap-3m-38mt-x-127mm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual\\\/atrapolvos\\\/caja-2-rollos-de-fibra-easy-trap-3m-38mt-x-127mm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/AM0009.jpg\",\"contentUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/AM0009.jpg\",\"width\":768,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/producto\\\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\\\/barrido-manual\\\/atrapolvos\\\/caja-2-rollos-de-fibra-easy-trap-3m-38mt-x-127mm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catalogue\",\"item\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/catalogue\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CAJA 2 ROLLOS DE FIBRA EASY TRAP 3M 38mt x 127mm &#8211; C\u00d3DIGO: AM0009\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\",\"name\":\"Meprolim\",\"description\":\"Cavas Catalanas S.L.\",\"publisher\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#organization\",\"name\":\"Meprolim\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-logo2.png\",\"contentUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-logo2.png\",\"width\":401,\"height\":162,\"caption\":\"Meprolim\"},\"image\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CAJA 2 ROLLOS DE FIBRA EASY TRAP 3M 38mt x 127mm - C\u00d3DIGO: AM0009 - Meprolim","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/meprolim.es\/fr\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/atrapolvos\/caja-2-rollos-de-fibra-easy-trap-3m-38mt-x-127mm\/","og_locale":"fr_FR","og_type":"article","og_title":"CAJA 2 ROLLOS DE FIBRA EASY TRAP 3M 38mt x 127mm - C\u00d3DIGO: AM0009 - Meprolim","og_description":"Caja 2 rollos 12,7 x 380 cm  Atrapa y retiene hasta seis veces m\u00e1s cantidad de polvo, suciedad y pelo que otras mopas tradicionales.  Dos anchos para adaptarse a cualquier soporte.  No deja residuos ni resinas sobre el suelo.  Pa\u00f1os recortados para facilitar su uso.  SKU: AM0009","og_url":"https:\/\/meprolim.es\/fr\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/atrapolvos\/caja-2-rollos-de-fibra-easy-trap-3m-38mt-x-127mm\/","og_site_name":"Meprolim","article_modified_time":"2019-10-29T19:17:33+00:00","og_image":[{"width":768,"height":768,"url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/AM0009.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/meprolim.es\/fr\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/atrapolvos\/caja-2-rollos-de-fibra-easy-trap-3m-38mt-x-127mm\/","url":"https:\/\/meprolim.es\/fr\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/atrapolvos\/caja-2-rollos-de-fibra-easy-trap-3m-38mt-x-127mm\/","name":"CAJA 2 ROLLOS DE FIBRA EASY TRAP 3M 38mt x 127mm - C\u00d3DIGO: AM0009 - Meprolim","isPartOf":{"@id":"https:\/\/meprolim.es\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/meprolim.es\/fr\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/atrapolvos\/caja-2-rollos-de-fibra-easy-trap-3m-38mt-x-127mm\/#primaryimage"},"image":{"@id":"https:\/\/meprolim.es\/fr\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/atrapolvos\/caja-2-rollos-de-fibra-easy-trap-3m-38mt-x-127mm\/#primaryimage"},"thumbnailUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/AM0009.jpg","datePublished":"2019-08-13T17:56:42+00:00","dateModified":"2019-10-29T19:17:33+00:00","breadcrumb":{"@id":"https:\/\/meprolim.es\/fr\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/atrapolvos\/caja-2-rollos-de-fibra-easy-trap-3m-38mt-x-127mm\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/meprolim.es\/fr\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/atrapolvos\/caja-2-rollos-de-fibra-easy-trap-3m-38mt-x-127mm\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/meprolim.es\/fr\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/atrapolvos\/caja-2-rollos-de-fibra-easy-trap-3m-38mt-x-127mm\/#primaryimage","url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/AM0009.jpg","contentUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/AM0009.jpg","width":768,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/meprolim.es\/fr\/producto\/carros-de-servicio-fregado-manual-y-articulos-de-limpieza\/barrido-manual\/atrapolvos\/caja-2-rollos-de-fibra-easy-trap-3m-38mt-x-127mm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/meprolim.es\/fr\/"},{"@type":"ListItem","position":2,"name":"Catalogue","item":"https:\/\/meprolim.es\/fr\/catalogue\/"},{"@type":"ListItem","position":3,"name":"CAJA 2 ROLLOS DE FIBRA EASY TRAP 3M 38mt x 127mm &#8211; C\u00d3DIGO: AM0009"}]},{"@type":"WebSite","@id":"https:\/\/meprolim.es\/fr\/#website","url":"https:\/\/meprolim.es\/fr\/","name":"Meprolim","description":"Cavas Catalanas S.L.","publisher":{"@id":"https:\/\/meprolim.es\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/meprolim.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/meprolim.es\/fr\/#organization","name":"Meprolim","url":"https:\/\/meprolim.es\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/meprolim.es\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/07\/cropped-logo2.png","contentUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/07\/cropped-logo2.png","width":401,"height":162,"caption":"Meprolim"},"image":{"@id":"https:\/\/meprolim.es\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/product\/5909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/media\/5910"}],"wp:attachment":[{"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/media?parent=5909"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/product_brand?post=5909"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/product_cat?post=5909"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/product_tag?post=5909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}