{"id":7117,"date":"2019-08-23T17:41:54","date_gmt":"2019-08-23T16:41:54","guid":{"rendered":"http:\/\/www.meprolim.es\/?post_type=product&#038;p=7117"},"modified":"2019-10-28T19:55:56","modified_gmt":"2019-10-28T19:55:56","slug":"caja-12x150-servilleta-tissue-39x39-roja-1-4","status":"publish","type":"product","link":"https:\/\/meprolim.es\/fr\/producto\/dispensadores-celulosa-y-complementos\/papel-servilletas-fr-2\/servilletas-fr-2\/calidad-tissu-fr-2\/39x39-fr-2\/caja-12x150-servilleta-tissue-39x39-roja-1-4\/","title":{"rendered":"CAJA 12&#215;150 SERVILLETA TISSUE 39&#215;39 ROJA 1\/4 &#8211; C\u00d3DIGO: CR1125"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">Tork Dinner Servilletas encajan en todas las ocasiones y aportan clase y son pr\u00e1cticas para el comedor. Hay una gran variedad de colores modernos y cl\u00e1sicos para corresponder a su decorado del restaurante.<\/p>\n<ul>\n<li style=\"text-align: justify;\">Alta calidad y absorci\u00f3n<\/li>\n<li style=\"text-align: justify;\">Servilleta de gran tama\u00f1o para una buena experiencia culinaria<\/li>\n<li style=\"text-align: justify;\">Amplia gama de colores cl\u00e1sicos y modernos<\/li>\n<li style=\"text-align: justify;\">Aprobaci\u00f3n contacto alimentario. EU Ecolabel .<\/li>\n<li style=\"text-align: justify;\">Tork Easy HandlingTM : F\u00e1cil de abrir, plegar y transportar<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<ul>\n<li>Calidad celulosa de dos capas.<\/li>\n<li>Dobladas en 1\/4.<\/li>\n<li>Color roja.<\/li>\n<li>Pack de 12 \/ 150 Unidades.<\/li>\n<li>Formato 39 x 39 cm\u00a0\u00a0<\/li>\n<\/ul>\n<p><strong>SKU: CR1125<\/strong><\/p>\n","protected":false},"featured_media":7118,"template":"","meta":[],"product_brand":[],"product_cat":[1126,1123,90,518,1119],"product_tag":[520],"class_list":["post-7117","product","type-product","status-publish","has-post-thumbnail","product_cat-39x39","product_cat-calidad-tissu","product_cat-complementos-para-banos-y-dispensadores","product_cat-papel-servilletas","product_cat-servilletas","product_tag-servilletas-de-servicio","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CAJA 12x150 SERVILLETA TISSUE 39x39 ROJA 1\/4 - C\u00d3DIGO: CR1125 - Meprolim<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/meprolim.es\/de\/producto\/complementos-para-banos-y-dispensadores\/papel-servilletas\/servilletas\/calidad-tissu\/39x39\/caja-12x150-servilleta-tissue-39x39-roja-1-4\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CAJA 12x150 SERVILLETA TISSUE 39x39 ROJA 1\/4 - C\u00d3DIGO: CR1125 - Meprolim\" \/>\n<meta property=\"og:description\" content=\"Calidad celulosa de dos capas.  Dobladas en 1\/4.  Color roja.  Pack de 12 \/ 150 Unidades.  Formato 39 x 39 cm\u00a0\u00a0  SKU: CR1125\" \/>\n<meta property=\"og:url\" content=\"https:\/\/meprolim.es\/de\/producto\/complementos-para-banos-y-dispensadores\/papel-servilletas\/servilletas\/calidad-tissu\/39x39\/caja-12x150-servilleta-tissue-39x39-roja-1-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Meprolim\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-28T19:55:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/CR1125.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/de\\\/producto\\\/complementos-para-banos-y-dispensadores\\\/papel-servilletas\\\/servilletas\\\/calidad-tissu\\\/39x39\\\/caja-12x150-servilleta-tissue-39x39-roja-1-4\\\/\",\"url\":\"https:\\\/\\\/meprolim.es\\\/de\\\/producto\\\/complementos-para-banos-y-dispensadores\\\/papel-servilletas\\\/servilletas\\\/calidad-tissu\\\/39x39\\\/caja-12x150-servilleta-tissue-39x39-roja-1-4\\\/\",\"name\":\"CAJA 12x150 SERVILLETA TISSUE 39x39 ROJA 1\\\/4 - C\u00d3DIGO: CR1125 - Meprolim\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/de\\\/producto\\\/complementos-para-banos-y-dispensadores\\\/papel-servilletas\\\/servilletas\\\/calidad-tissu\\\/39x39\\\/caja-12x150-servilleta-tissue-39x39-roja-1-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/de\\\/producto\\\/complementos-para-banos-y-dispensadores\\\/papel-servilletas\\\/servilletas\\\/calidad-tissu\\\/39x39\\\/caja-12x150-servilleta-tissue-39x39-roja-1-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/CR1125.jpg\",\"datePublished\":\"2019-08-23T16:41:54+00:00\",\"dateModified\":\"2019-10-28T19:55:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/de\\\/producto\\\/complementos-para-banos-y-dispensadores\\\/papel-servilletas\\\/servilletas\\\/calidad-tissu\\\/39x39\\\/caja-12x150-servilleta-tissue-39x39-roja-1-4\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/meprolim.es\\\/de\\\/producto\\\/complementos-para-banos-y-dispensadores\\\/papel-servilletas\\\/servilletas\\\/calidad-tissu\\\/39x39\\\/caja-12x150-servilleta-tissue-39x39-roja-1-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/de\\\/producto\\\/complementos-para-banos-y-dispensadores\\\/papel-servilletas\\\/servilletas\\\/calidad-tissu\\\/39x39\\\/caja-12x150-servilleta-tissue-39x39-roja-1-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/CR1125.jpg\",\"contentUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/CR1125.jpg\",\"width\":768,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/de\\\/producto\\\/complementos-para-banos-y-dispensadores\\\/papel-servilletas\\\/servilletas\\\/calidad-tissu\\\/39x39\\\/caja-12x150-servilleta-tissue-39x39-roja-1-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catalogue\",\"item\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/catalogue\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CAJA 12&#215;150 SERVILLETA TISSUE 39&#215;39 ROJA 1\\\/4 &#8211; C\u00d3DIGO: CR1125\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\",\"name\":\"Meprolim\",\"description\":\"Cavas Catalanas S.L.\",\"publisher\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#organization\",\"name\":\"Meprolim\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-logo2.png\",\"contentUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-logo2.png\",\"width\":401,\"height\":162,\"caption\":\"Meprolim\"},\"image\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CAJA 12x150 SERVILLETA TISSUE 39x39 ROJA 1\/4 - C\u00d3DIGO: CR1125 - Meprolim","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/meprolim.es\/de\/producto\/complementos-para-banos-y-dispensadores\/papel-servilletas\/servilletas\/calidad-tissu\/39x39\/caja-12x150-servilleta-tissue-39x39-roja-1-4\/","og_locale":"fr_FR","og_type":"article","og_title":"CAJA 12x150 SERVILLETA TISSUE 39x39 ROJA 1\/4 - C\u00d3DIGO: CR1125 - Meprolim","og_description":"Calidad celulosa de dos capas.  Dobladas en 1\/4.  Color roja.  Pack de 12 \/ 150 Unidades.  Formato 39 x 39 cm\u00a0\u00a0  SKU: CR1125","og_url":"https:\/\/meprolim.es\/de\/producto\/complementos-para-banos-y-dispensadores\/papel-servilletas\/servilletas\/calidad-tissu\/39x39\/caja-12x150-servilleta-tissue-39x39-roja-1-4\/","og_site_name":"Meprolim","article_modified_time":"2019-10-28T19:55:56+00:00","og_image":[{"width":768,"height":768,"url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/CR1125.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/meprolim.es\/de\/producto\/complementos-para-banos-y-dispensadores\/papel-servilletas\/servilletas\/calidad-tissu\/39x39\/caja-12x150-servilleta-tissue-39x39-roja-1-4\/","url":"https:\/\/meprolim.es\/de\/producto\/complementos-para-banos-y-dispensadores\/papel-servilletas\/servilletas\/calidad-tissu\/39x39\/caja-12x150-servilleta-tissue-39x39-roja-1-4\/","name":"CAJA 12x150 SERVILLETA TISSUE 39x39 ROJA 1\/4 - C\u00d3DIGO: CR1125 - Meprolim","isPartOf":{"@id":"https:\/\/meprolim.es\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/meprolim.es\/de\/producto\/complementos-para-banos-y-dispensadores\/papel-servilletas\/servilletas\/calidad-tissu\/39x39\/caja-12x150-servilleta-tissue-39x39-roja-1-4\/#primaryimage"},"image":{"@id":"https:\/\/meprolim.es\/de\/producto\/complementos-para-banos-y-dispensadores\/papel-servilletas\/servilletas\/calidad-tissu\/39x39\/caja-12x150-servilleta-tissue-39x39-roja-1-4\/#primaryimage"},"thumbnailUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/CR1125.jpg","datePublished":"2019-08-23T16:41:54+00:00","dateModified":"2019-10-28T19:55:56+00:00","breadcrumb":{"@id":"https:\/\/meprolim.es\/de\/producto\/complementos-para-banos-y-dispensadores\/papel-servilletas\/servilletas\/calidad-tissu\/39x39\/caja-12x150-servilleta-tissue-39x39-roja-1-4\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/meprolim.es\/de\/producto\/complementos-para-banos-y-dispensadores\/papel-servilletas\/servilletas\/calidad-tissu\/39x39\/caja-12x150-servilleta-tissue-39x39-roja-1-4\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/meprolim.es\/de\/producto\/complementos-para-banos-y-dispensadores\/papel-servilletas\/servilletas\/calidad-tissu\/39x39\/caja-12x150-servilleta-tissue-39x39-roja-1-4\/#primaryimage","url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/CR1125.jpg","contentUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/CR1125.jpg","width":768,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/meprolim.es\/de\/producto\/complementos-para-banos-y-dispensadores\/papel-servilletas\/servilletas\/calidad-tissu\/39x39\/caja-12x150-servilleta-tissue-39x39-roja-1-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/meprolim.es\/fr\/"},{"@type":"ListItem","position":2,"name":"Catalogue","item":"https:\/\/meprolim.es\/fr\/catalogue\/"},{"@type":"ListItem","position":3,"name":"CAJA 12&#215;150 SERVILLETA TISSUE 39&#215;39 ROJA 1\/4 &#8211; C\u00d3DIGO: CR1125"}]},{"@type":"WebSite","@id":"https:\/\/meprolim.es\/fr\/#website","url":"https:\/\/meprolim.es\/fr\/","name":"Meprolim","description":"Cavas Catalanas S.L.","publisher":{"@id":"https:\/\/meprolim.es\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/meprolim.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/meprolim.es\/fr\/#organization","name":"Meprolim","url":"https:\/\/meprolim.es\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/meprolim.es\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/07\/cropped-logo2.png","contentUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/07\/cropped-logo2.png","width":401,"height":162,"caption":"Meprolim"},"image":{"@id":"https:\/\/meprolim.es\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/product\/7117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/media\/7118"}],"wp:attachment":[{"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/media?parent=7117"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/product_brand?post=7117"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/product_cat?post=7117"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/product_tag?post=7117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}