{"id":7292,"date":"2019-08-24T21:39:15","date_gmt":"2019-08-24T20:39:15","guid":{"rendered":"http:\/\/www.meprolim.es\/?post_type=product&#038;p=7292"},"modified":"2019-10-16T15:07:33","modified_gmt":"2019-10-16T14:07:33","slug":"cenicero-pole-plateado","status":"publish","type":"product","link":"https:\/\/meprolim.es\/fr\/producto\/dispensadores-celulosa-y-complementos\/papeleras-ceniceros-fr-2\/ceniceros-fr-2\/cenicero-pole-plateado\/","title":{"rendered":"CENICERO POLE PLATEADO . C\u00d3DIGO: BK0241"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<p>Cenicero-colillero de exterior en color gris.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u2022 Base con peso.<\/p>\n<p>\u2022 Resistentes al fuego y la intemperie.<\/p>\n<p><strong>SKU: BK0241<\/strong><\/p>\n","protected":false},"featured_media":7293,"template":"","meta":[],"product_brand":[],"product_cat":[533,90,422],"product_tag":[534],"class_list":["post-7292","product","type-product","status-publish","has-post-thumbnail","product_cat-ceniceros","product_cat-complementos-para-banos-y-dispensadores","product_cat-papeleras-ceniceros","product_tag-ceniceros-metalicos-de-suelo","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CENICERO POLE PLATEADO . C\u00d3DIGO: BK0241 - Meprolim<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/meprolim.es\/fr\/producto\/complementos-para-banos-y-dispensadores\/papeleras-ceniceros\/ceniceros\/cenicero-pole-plateado\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CENICERO POLE PLATEADO . C\u00d3DIGO: BK0241 - Meprolim\" \/>\n<meta property=\"og:description\" content=\"\u2022 Base con peso. \u2022 Resistentes al fuego y la intemperie. SKU: BK0241\" \/>\n<meta property=\"og:url\" content=\"https:\/\/meprolim.es\/fr\/producto\/complementos-para-banos-y-dispensadores\/papeleras-ceniceros\/ceniceros\/cenicero-pole-plateado\/\" \/>\n<meta property=\"og:site_name\" content=\"Meprolim\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-16T14:07:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/BK0241.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"773\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/producto\\\/complementos-para-banos-y-dispensadores\\\/papeleras-ceniceros\\\/ceniceros\\\/cenicero-pole-plateado\\\/\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/producto\\\/complementos-para-banos-y-dispensadores\\\/papeleras-ceniceros\\\/ceniceros\\\/cenicero-pole-plateado\\\/\",\"name\":\"CENICERO POLE PLATEADO . C\u00d3DIGO: BK0241 - Meprolim\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/producto\\\/complementos-para-banos-y-dispensadores\\\/papeleras-ceniceros\\\/ceniceros\\\/cenicero-pole-plateado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/producto\\\/complementos-para-banos-y-dispensadores\\\/papeleras-ceniceros\\\/ceniceros\\\/cenicero-pole-plateado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/BK0241.jpg\",\"datePublished\":\"2019-08-24T20:39:15+00:00\",\"dateModified\":\"2019-10-16T14:07:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/producto\\\/complementos-para-banos-y-dispensadores\\\/papeleras-ceniceros\\\/ceniceros\\\/cenicero-pole-plateado\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/meprolim.es\\\/fr\\\/producto\\\/complementos-para-banos-y-dispensadores\\\/papeleras-ceniceros\\\/ceniceros\\\/cenicero-pole-plateado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/producto\\\/complementos-para-banos-y-dispensadores\\\/papeleras-ceniceros\\\/ceniceros\\\/cenicero-pole-plateado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/BK0241.jpg\",\"contentUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/BK0241.jpg\",\"width\":768,\"height\":773},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/producto\\\/complementos-para-banos-y-dispensadores\\\/papeleras-ceniceros\\\/ceniceros\\\/cenicero-pole-plateado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catalogue\",\"item\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/catalogue\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CENICERO POLE PLATEADO . C\u00d3DIGO: BK0241\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\",\"name\":\"Meprolim\",\"description\":\"Cavas Catalanas S.L.\",\"publisher\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#organization\",\"name\":\"Meprolim\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-logo2.png\",\"contentUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-logo2.png\",\"width\":401,\"height\":162,\"caption\":\"Meprolim\"},\"image\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CENICERO POLE PLATEADO . C\u00d3DIGO: BK0241 - Meprolim","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/meprolim.es\/fr\/producto\/complementos-para-banos-y-dispensadores\/papeleras-ceniceros\/ceniceros\/cenicero-pole-plateado\/","og_locale":"fr_FR","og_type":"article","og_title":"CENICERO POLE PLATEADO . C\u00d3DIGO: BK0241 - Meprolim","og_description":"\u2022 Base con peso. \u2022 Resistentes al fuego y la intemperie. SKU: BK0241","og_url":"https:\/\/meprolim.es\/fr\/producto\/complementos-para-banos-y-dispensadores\/papeleras-ceniceros\/ceniceros\/cenicero-pole-plateado\/","og_site_name":"Meprolim","article_modified_time":"2019-10-16T14:07:33+00:00","og_image":[{"width":768,"height":773,"url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/BK0241.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/meprolim.es\/fr\/producto\/complementos-para-banos-y-dispensadores\/papeleras-ceniceros\/ceniceros\/cenicero-pole-plateado\/","url":"https:\/\/meprolim.es\/fr\/producto\/complementos-para-banos-y-dispensadores\/papeleras-ceniceros\/ceniceros\/cenicero-pole-plateado\/","name":"CENICERO POLE PLATEADO . C\u00d3DIGO: BK0241 - Meprolim","isPartOf":{"@id":"https:\/\/meprolim.es\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/meprolim.es\/fr\/producto\/complementos-para-banos-y-dispensadores\/papeleras-ceniceros\/ceniceros\/cenicero-pole-plateado\/#primaryimage"},"image":{"@id":"https:\/\/meprolim.es\/fr\/producto\/complementos-para-banos-y-dispensadores\/papeleras-ceniceros\/ceniceros\/cenicero-pole-plateado\/#primaryimage"},"thumbnailUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/BK0241.jpg","datePublished":"2019-08-24T20:39:15+00:00","dateModified":"2019-10-16T14:07:33+00:00","breadcrumb":{"@id":"https:\/\/meprolim.es\/fr\/producto\/complementos-para-banos-y-dispensadores\/papeleras-ceniceros\/ceniceros\/cenicero-pole-plateado\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/meprolim.es\/fr\/producto\/complementos-para-banos-y-dispensadores\/papeleras-ceniceros\/ceniceros\/cenicero-pole-plateado\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/meprolim.es\/fr\/producto\/complementos-para-banos-y-dispensadores\/papeleras-ceniceros\/ceniceros\/cenicero-pole-plateado\/#primaryimage","url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/BK0241.jpg","contentUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/08\/BK0241.jpg","width":768,"height":773},{"@type":"BreadcrumbList","@id":"https:\/\/meprolim.es\/fr\/producto\/complementos-para-banos-y-dispensadores\/papeleras-ceniceros\/ceniceros\/cenicero-pole-plateado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/meprolim.es\/fr\/"},{"@type":"ListItem","position":2,"name":"Catalogue","item":"https:\/\/meprolim.es\/fr\/catalogue\/"},{"@type":"ListItem","position":3,"name":"CENICERO POLE PLATEADO . C\u00d3DIGO: BK0241"}]},{"@type":"WebSite","@id":"https:\/\/meprolim.es\/fr\/#website","url":"https:\/\/meprolim.es\/fr\/","name":"Meprolim","description":"Cavas Catalanas S.L.","publisher":{"@id":"https:\/\/meprolim.es\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/meprolim.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/meprolim.es\/fr\/#organization","name":"Meprolim","url":"https:\/\/meprolim.es\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/meprolim.es\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/07\/cropped-logo2.png","contentUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/07\/cropped-logo2.png","width":401,"height":162,"caption":"Meprolim"},"image":{"@id":"https:\/\/meprolim.es\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/product\/7292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/media\/7293"}],"wp:attachment":[{"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/media?parent=7292"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/product_brand?post=7292"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/product_cat?post=7292"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/product_tag?post=7292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}