{"id":8730,"date":"2019-09-03T06:36:39","date_gmt":"2019-09-03T05:36:39","guid":{"rendered":"http:\/\/www.meprolim.es\/?post_type=product&#038;p=8730"},"modified":"2019-10-18T14:59:40","modified_gmt":"2019-10-18T13:59:40","slug":"dispensador-sanimatic-cp-tazas-wc","status":"publish","type":"product","link":"https:\/\/meprolim.es\/fr\/producto\/dispensadores-celulosa-y-complementos\/bacterostaticos-fr-2\/bx4094-fr-2\/dispensador-sanimatic-cp-tazas-wc\/","title":{"rendered":"DISPENSADOR SANIMATIC CP (TAZAS WC) &#8211; C\u00d3DIGO: BX4118"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<p>Dosificador para taza WC en ABS blanco.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u2022 Dosificador en ABS blanco con cierre.<\/p>\n<p>\u2022 Dep\u00f3sito rellenable de 720 ml.<\/p>\n<p>\u2022 Tubo de acero inoxidable con sistema anti-retorno.<\/p>\n<p>\u2022 V\u00e1lido para urinarios o cisternas de funcionamiento hidr\u00e1ulico.<\/p>\n<p>\u2022 No lleva pilas (sin mantenimiento).<\/p>\n<p><strong>SKU: BX4118<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":8731,"template":"","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":""},"product_brand":[],"product_cat":[1134,741,90],"product_tag":[722,743,742],"class_list":["post-8730","product","type-product","status-publish","has-post-thumbnail","product_cat-bacterostaticos","product_cat-bx4094","product_cat-complementos-para-banos-y-dispensadores","product_tag-ambientadores","product_tag-bacteriostatico","product_tag-bacteriostatico-ambientador","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DISPENSADOR SANIMATIC CP (TAZAS WC) - C\u00d3DIGO: BX4118 - Meprolim<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/meprolim.es\/fr\/producto\/complementos-para-banos-y-dispensadores\/bacterostaticos\/bx4094\/dispensador-sanimatic-cp-tazas-wc\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DISPENSADOR SANIMATIC CP (TAZAS WC) - C\u00d3DIGO: BX4118 - Meprolim\" \/>\n<meta property=\"og:description\" content=\"\u2022 Dosificador en ABS blanco con cierre. \u2022 Dep\u00f3sito rellenable de 720 ml. \u2022 Tubo de acero inoxidable con sistema anti-retorno. \u2022 V\u00e1lido para urinarios o cisternas de funcionamiento hidr\u00e1ulico. \u2022 No lleva pilas (sin mantenimiento). SKU: BX4118 &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/meprolim.es\/fr\/producto\/complementos-para-banos-y-dispensadores\/bacterostaticos\/bx4094\/dispensador-sanimatic-cp-tazas-wc\/\" \/>\n<meta property=\"og:site_name\" content=\"Meprolim\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-18T13:59:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/09\/BX4118.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/producto\\\/complementos-para-banos-y-dispensadores\\\/bacterostaticos\\\/bx4094\\\/dispensador-sanimatic-cp-tazas-wc\\\/\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/producto\\\/complementos-para-banos-y-dispensadores\\\/bacterostaticos\\\/bx4094\\\/dispensador-sanimatic-cp-tazas-wc\\\/\",\"name\":\"DISPENSADOR SANIMATIC CP (TAZAS WC) - C\u00d3DIGO: BX4118 - Meprolim\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/producto\\\/complementos-para-banos-y-dispensadores\\\/bacterostaticos\\\/bx4094\\\/dispensador-sanimatic-cp-tazas-wc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/producto\\\/complementos-para-banos-y-dispensadores\\\/bacterostaticos\\\/bx4094\\\/dispensador-sanimatic-cp-tazas-wc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/BX4118.jpg\",\"datePublished\":\"2019-09-03T05:36:39+00:00\",\"dateModified\":\"2019-10-18T13:59:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/producto\\\/complementos-para-banos-y-dispensadores\\\/bacterostaticos\\\/bx4094\\\/dispensador-sanimatic-cp-tazas-wc\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/meprolim.es\\\/fr\\\/producto\\\/complementos-para-banos-y-dispensadores\\\/bacterostaticos\\\/bx4094\\\/dispensador-sanimatic-cp-tazas-wc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/producto\\\/complementos-para-banos-y-dispensadores\\\/bacterostaticos\\\/bx4094\\\/dispensador-sanimatic-cp-tazas-wc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/BX4118.jpg\",\"contentUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/BX4118.jpg\",\"width\":768,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/producto\\\/complementos-para-banos-y-dispensadores\\\/bacterostaticos\\\/bx4094\\\/dispensador-sanimatic-cp-tazas-wc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catalogue\",\"item\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/catalogue\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DISPENSADOR SANIMATIC CP (TAZAS WC) &#8211; C\u00d3DIGO: BX4118\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\",\"name\":\"Meprolim\",\"description\":\"Cavas Catalanas S.L.\",\"publisher\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#organization\",\"name\":\"Meprolim\",\"url\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-logo2.png\",\"contentUrl\":\"https:\\\/\\\/meprolim.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-logo2.png\",\"width\":401,\"height\":162,\"caption\":\"Meprolim\"},\"image\":{\"@id\":\"https:\\\/\\\/meprolim.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DISPENSADOR SANIMATIC CP (TAZAS WC) - C\u00d3DIGO: BX4118 - Meprolim","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/meprolim.es\/fr\/producto\/complementos-para-banos-y-dispensadores\/bacterostaticos\/bx4094\/dispensador-sanimatic-cp-tazas-wc\/","og_locale":"fr_FR","og_type":"article","og_title":"DISPENSADOR SANIMATIC CP (TAZAS WC) - C\u00d3DIGO: BX4118 - Meprolim","og_description":"\u2022 Dosificador en ABS blanco con cierre. \u2022 Dep\u00f3sito rellenable de 720 ml. \u2022 Tubo de acero inoxidable con sistema anti-retorno. \u2022 V\u00e1lido para urinarios o cisternas de funcionamiento hidr\u00e1ulico. \u2022 No lleva pilas (sin mantenimiento). SKU: BX4118 &nbsp;","og_url":"https:\/\/meprolim.es\/fr\/producto\/complementos-para-banos-y-dispensadores\/bacterostaticos\/bx4094\/dispensador-sanimatic-cp-tazas-wc\/","og_site_name":"Meprolim","article_modified_time":"2019-10-18T13:59:40+00:00","og_image":[{"width":768,"height":768,"url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/09\/BX4118.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/meprolim.es\/fr\/producto\/complementos-para-banos-y-dispensadores\/bacterostaticos\/bx4094\/dispensador-sanimatic-cp-tazas-wc\/","url":"https:\/\/meprolim.es\/fr\/producto\/complementos-para-banos-y-dispensadores\/bacterostaticos\/bx4094\/dispensador-sanimatic-cp-tazas-wc\/","name":"DISPENSADOR SANIMATIC CP (TAZAS WC) - C\u00d3DIGO: BX4118 - Meprolim","isPartOf":{"@id":"https:\/\/meprolim.es\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/meprolim.es\/fr\/producto\/complementos-para-banos-y-dispensadores\/bacterostaticos\/bx4094\/dispensador-sanimatic-cp-tazas-wc\/#primaryimage"},"image":{"@id":"https:\/\/meprolim.es\/fr\/producto\/complementos-para-banos-y-dispensadores\/bacterostaticos\/bx4094\/dispensador-sanimatic-cp-tazas-wc\/#primaryimage"},"thumbnailUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/09\/BX4118.jpg","datePublished":"2019-09-03T05:36:39+00:00","dateModified":"2019-10-18T13:59:40+00:00","breadcrumb":{"@id":"https:\/\/meprolim.es\/fr\/producto\/complementos-para-banos-y-dispensadores\/bacterostaticos\/bx4094\/dispensador-sanimatic-cp-tazas-wc\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/meprolim.es\/fr\/producto\/complementos-para-banos-y-dispensadores\/bacterostaticos\/bx4094\/dispensador-sanimatic-cp-tazas-wc\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/meprolim.es\/fr\/producto\/complementos-para-banos-y-dispensadores\/bacterostaticos\/bx4094\/dispensador-sanimatic-cp-tazas-wc\/#primaryimage","url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/09\/BX4118.jpg","contentUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/09\/BX4118.jpg","width":768,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/meprolim.es\/fr\/producto\/complementos-para-banos-y-dispensadores\/bacterostaticos\/bx4094\/dispensador-sanimatic-cp-tazas-wc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/meprolim.es\/fr\/"},{"@type":"ListItem","position":2,"name":"Catalogue","item":"https:\/\/meprolim.es\/fr\/catalogue\/"},{"@type":"ListItem","position":3,"name":"DISPENSADOR SANIMATIC CP (TAZAS WC) &#8211; C\u00d3DIGO: BX4118"}]},{"@type":"WebSite","@id":"https:\/\/meprolim.es\/fr\/#website","url":"https:\/\/meprolim.es\/fr\/","name":"Meprolim","description":"Cavas Catalanas S.L.","publisher":{"@id":"https:\/\/meprolim.es\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/meprolim.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/meprolim.es\/fr\/#organization","name":"Meprolim","url":"https:\/\/meprolim.es\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/meprolim.es\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/07\/cropped-logo2.png","contentUrl":"https:\/\/meprolim.es\/wp-content\/uploads\/2019\/07\/cropped-logo2.png","width":401,"height":162,"caption":"Meprolim"},"image":{"@id":"https:\/\/meprolim.es\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/product\/8730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/media\/8731"}],"wp:attachment":[{"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/media?parent=8730"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/product_brand?post=8730"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/product_cat?post=8730"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/meprolim.es\/fr\/wp-json\/wp\/v2\/product_tag?post=8730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}